{"id":30020,"count":1,"description":"","link":"https:\/\/missav.video\/vi\/actor\/seo-reiko-vi\/","name":"Seo Reiko","slug":"seo-reiko-vi","taxonomy":"actors","meta":[],"_links":{"self":[{"href":"https:\/\/missav.video\/vi\/wp-json\/wp\/v2\/actors\/30020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/missav.video\/vi\/wp-json\/wp\/v2\/actors"}],"about":[{"href":"https:\/\/missav.video\/vi\/wp-json\/wp\/v2\/taxonomies\/actors"}],"wp:post_type":[{"href":"https:\/\/missav.video\/vi\/wp-json\/wp\/v2\/posts?actors=30020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}