{"id":28967,"date":"2024-09-04T08:15:52","date_gmt":"2024-09-04T01:15:52","guid":{"rendered":"https:\/\/thisav.me\/dasd-788-uma-casa-especial-ja-satisfeita-com-um-fantasma\/"},"modified":"2024-12-11T16:48:06","modified_gmt":"2024-12-11T09:48:06","slug":"dasd-788-uma-casa-especial-ja-satisfeita-com-um-fantasma","status":"publish","type":"post","link":"https:\/\/missav.video\/pt-br\/dasd-788-uma-casa-especial-ja-satisfeita-com-um-fantasma\/","title":{"rendered":"DASD-788 Uma casa especial j\u00e1 satisfeita com um fantasma"},"content":{"rendered":"<p>DASD-788 Uma casa especial que j\u00e1 ficou satisfeita com um fantasma Mahiro Ichiki Sinopse O casal mudou-se para uma casa relativamente antiga. Seu marido encontrou algo estranho. Ele viu o esp\u00edrito de uma garota na casa, mesmo quando ele e sua esposa estavam fazendo sexo. A garota fantasma tamb\u00e9m veio se juntar \u00e0 jam.<br \/>\n<iframe loading=\"lazy\" class=\"videowrapper\" src=\"https:\/\/fembeqq.xyz\/player\/index.php?data=b7396ce9467ba9aa6d556b7af07ab4e5\" width=\"300\" height=\"175\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DASD-788 Uma casa especial que j\u00e1 ficou satisfeita com um fantasma Mahiro Ichiki Sinopse O casal mudou-se para uma casa relativamente antiga. Seu marido encontrou algo estranho. Ele viu o esp\u00edrito de uma garota na casa, mesmo quando ele e sua esposa estavam fazendo sexo. A garota fantasma tamb\u00e9m veio se juntar \u00e0 jam. [&#8230;]<\/p>\n<p><a class=\"btn btn-primary wpst-read-more-link\" href=\"https:\/\/missav.video\/pt-br\/dasd-788-uma-casa-especial-ja-satisfeita-com-um-fantasma\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":28951,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[114,279,684],"tags":[4100,6496,323,12158],"actors":[10191],"class_list":["post-28967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-assista-jav","category-av-ntr-pt-br","category-familia-av","tag-copo-c","tag-dasd-pt-br","tag-menina-de-cabelo-curto","tag-uniformes-escolares","actors-mahiro-ichiki-pt-br"],"_links":{"self":[{"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/posts\/28967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/comments?post=28967"}],"version-history":[{"count":0,"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/posts\/28967\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/media\/28951"}],"wp:attachment":[{"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/media?parent=28967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/categories?post=28967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/tags?post=28967"},{"taxonomy":"actors","embeddable":true,"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/actors?post=28967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}