{"id":130069,"date":"2026-03-17T21:06:50","date_gmt":"2026-03-17T14:06:50","guid":{"rendered":"https:\/\/thisav.me\/dldss-015-novo-brinquedo-da-sra-general\/"},"modified":"2026-03-17T21:06:50","modified_gmt":"2026-03-17T14:06:50","slug":"dldss-015-novo-brinquedo-da-sra-general","status":"publish","type":"post","link":"https:\/\/missav.video\/pt-br\/dldss-015-novo-brinquedo-da-sra-general\/","title":{"rendered":"DLDSS-015 Novo Brinquedo da Sra. General"},"content":{"rendered":"<p>DLDSS-015 Sinopse do Novo Brinquedo da Sra. Suzume Mino Outra hist\u00f3ria da garota de alto padr\u00e3o. Mas o desejo sexual nunca divide classes. Quando ela conheceu aquele desgra\u00e7ado, parecia que estava prestes a ganhar um brinquedo novo.<br \/>\n<iframe loading=\"lazy\" class=\"videowrapper\" src=\"https:\/\/fembeqq.xyz\/player\/index.php?data=421f8eb2f6d635fc5e09d0b16c59e281\" width=\"300\" height=\"175\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DLDSS-015 Sinopse do Novo Brinquedo da Sra. Suzume Mino Outra hist\u00f3ria da garota de alto padr\u00e3o. Mas o desejo sexual nunca divide classes. Quando ela conheceu aquele desgra\u00e7ado, parecia que estava prestes a ganhar um brinquedo novo. [&#8230;]<\/p>\n<p><a class=\"btn btn-primary wpst-read-more-link\" href=\"https:\/\/missav.video\/pt-br\/dldss-015-novo-brinquedo-da-sra-general\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":129820,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[114,279],"tags":[7497,323,1177],"actors":[18390],"class_list":["post-130069","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-assista-jav","category-av-ntr-pt-br","tag-dldss-pt-br","tag-menina-de-cabelo-curto","tag-tentar","actors-suzume-mino-pt-br"],"_links":{"self":[{"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/posts\/130069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/comments?post=130069"}],"version-history":[{"count":0,"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/posts\/130069\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/media\/129820"}],"wp:attachment":[{"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/media?parent=130069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/categories?post=130069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/tags?post=130069"},{"taxonomy":"actors","embeddable":true,"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/actors?post=130069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}