{"id":120398,"date":"2026-02-01T17:03:31","date_gmt":"2026-02-01T10:03:31","guid":{"rendered":"https:\/\/thisav.me\/hsoda-059-garoto-bonito-estudando-dever-de-casa\/"},"modified":"2026-02-01T17:07:19","modified_gmt":"2026-02-01T10:07:19","slug":"hsoda-059-garoto-bonito-estudando-dever-de-casa","status":"publish","type":"post","link":"https:\/\/missav.video\/pt-br\/hsoda-059-garoto-bonito-estudando-dever-de-casa\/","title":{"rendered":"HSODA-059 Garoto Bonito Estudando Dever de Casa"},"content":{"rendered":"<p>  HSODA-059 Garoto Bonito Estudando Dever de Casa Sinopse: \u00c9 sobre um jovem estudante que \u00e9 diligente em seus deveres. S\u00f3 existem alunas que adoram se arrumar, mas se recusam a fazer o dever de casa. Ent\u00e3o usaram o m\u00e9todo de dar sexo como compensa\u00e7\u00e3o. Copiar o dever de casa todos os dias depois da escola. Esse \u00e9 o sonho que esse jovem realmente quer.<br \/>\n<iframe loading=\"lazy\" class=\"videowrapper\" src=\"https:\/\/fembeqv2.xyz\/player\/index.php?data=77ee3bc58ce560b86c2b59363281e914\" width=\"300\" height=\"175\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>HSODA-059 Garoto Bonito Estudando Dever de Casa Sinopse: \u00c9 sobre um jovem estudante que \u00e9 diligente em seus deveres. S\u00f3 existem alunas que adoram se arrumar, mas se recusam a fazer o dever de casa. Ent\u00e3o usaram o m\u00e9todo de dar sexo como compensa\u00e7\u00e3o. Copiar o dever de casa todos os dias depois da escola. [&#8230;]<\/p>\n<p><a class=\"btn btn-primary wpst-read-more-link\" href=\"https:\/\/missav.video\/pt-br\/hsoda-059-garoto-bonito-estudando-dever-de-casa\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":120304,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[114,115],"tags":[174,1609,224,2063,2535],"actors":[32643,15843,42205,20590,11866],"class_list":["post-120398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-assista-jav","category-vazamento-sem-censura","tag-calvo","tag-estudante","tag-gozar-dentro","tag-hsoda-pt-br","tag-sexo-na-escola","actors-kawaei-yua-pt-br","actors-kurumi-sakura-pt-br","actors-maeda-minami-pt-br","actors-minasuki-hikaru-pt-br","actors-tsukino-kasumi-pt-br"],"_links":{"self":[{"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/posts\/120398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/comments?post=120398"}],"version-history":[{"count":0,"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/posts\/120398\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/media\/120304"}],"wp:attachment":[{"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/media?parent=120398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/categories?post=120398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/tags?post=120398"},{"taxonomy":"actors","embeddable":true,"href":"https:\/\/missav.video\/pt-br\/wp-json\/wp\/v2\/actors?post=120398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}