{"id":141427,"date":"2026-05-09T15:37:39","date_gmt":"2026-05-09T08:37:39","guid":{"rendered":"https:\/\/thisav.me\/mdyd-991-begraebnis-mit-leib-und-seele\/"},"modified":"2026-05-09T15:37:39","modified_gmt":"2026-05-09T08:37:39","slug":"mdyd-991-begraebnis-mit-leib-und-seele","status":"publish","type":"post","link":"https:\/\/missav.video\/de\/mdyd-991-begraebnis-mit-leib-und-seele\/","title":{"rendered":"MDYD-991 Begr\u00e4bnis mit Leib und Seele"},"content":{"rendered":"<p>MDYD-991 Begr\u00e4bnis mit beschr\u00e4nktem K\u00f6rper und Seele Mako Oda Zusammenfassung Eine junge Lehrerin, die von einem Sch\u00fcler bei der Organisation einer Veranstaltung in ihrem Haus unterst\u00fctzt wurde. Als ihr Mann mehrere Tage weg war, sperrte sie ihren K\u00f6rper ein und verz\u00f6gerte den der jungen Lehrerin, bis der Sch\u00fcler tief in ihrer Seele vergraben war, sodass sie vor Aufregung ein L\u00e4cheln herausrei\u00dfen musste.<br \/>\n<iframe loading=\"lazy\" class=\"videowrapper\" src=\"https:\/\/fembeqv2.xyz\/player\/index.php?data=c8d12113e2258af31914e88130b917f6\" width=\"300\" height=\"175\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MDYD-991 Begr\u00e4bnis mit beschr\u00e4nktem K\u00f6rper und Seele Mako Oda Zusammenfassung Eine junge Lehrerin, die von einem Sch\u00fcler bei der Organisation einer Veranstaltung in ihrem Haus unterst\u00fctzt wurde. Als ihr Mann mehrere Tage weg war, sperrte sie ihren K\u00f6rper ein und verz\u00f6gerte den der jungen Lehrerin, bis der Sch\u00fcler tief in ihrer Seele vergraben war, sodass [&#8230;]<\/p>\n<p><a class=\"btn btn-primary wpst-read-more-link\" href=\"https:\/\/missav.video\/de\/mdyd-991-begraebnis-mit-leib-und-seele\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":141362,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[255,829,577,106,107],"tags":[204,203,10781],"actors":[32913],"class_list":["post-141427","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-av-ntr-de","category-av-lehramtsstudent","category-av-vergewaltigung","category-jav-ansehen","category-unzensiertes-leck","tag-cum-innen","tag-gros","tag-mdyd-de","actors-mako-oda-de"],"_links":{"self":[{"href":"https:\/\/missav.video\/de\/wp-json\/wp\/v2\/posts\/141427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/missav.video\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/missav.video\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/missav.video\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/missav.video\/de\/wp-json\/wp\/v2\/comments?post=141427"}],"version-history":[{"count":0,"href":"https:\/\/missav.video\/de\/wp-json\/wp\/v2\/posts\/141427\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/missav.video\/de\/wp-json\/wp\/v2\/media\/141362"}],"wp:attachment":[{"href":"https:\/\/missav.video\/de\/wp-json\/wp\/v2\/media?parent=141427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/missav.video\/de\/wp-json\/wp\/v2\/categories?post=141427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/missav.video\/de\/wp-json\/wp\/v2\/tags?post=141427"},{"taxonomy":"actors","embeddable":true,"href":"https:\/\/missav.video\/de\/wp-json\/wp\/v2\/actors?post=141427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}