{"id":28237,"count":3,"description":"","link":"https:\/\/missav.video\/de\/actor\/cookiecreamasia-de\/","name":"CookieCreamAsia","slug":"cookiecreamasia-de","taxonomy":"actors","meta":[],"_links":{"self":[{"href":"https:\/\/missav.video\/de\/wp-json\/wp\/v2\/actors\/28237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/missav.video\/de\/wp-json\/wp\/v2\/actors"}],"about":[{"href":"https:\/\/missav.video\/de\/wp-json\/wp\/v2\/taxonomies\/actors"}],"wp:post_type":[{"href":"https:\/\/missav.video\/de\/wp-json\/wp\/v2\/posts?actors=28237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}